{"id":3566,"date":"2023-12-23T17:06:26","date_gmt":"2023-12-23T17:06:26","guid":{"rendered":"https:\/\/gorgeousturkeytours.com\/tours\/excursion-roja-privada\/"},"modified":"2025-05-18T08:07:26","modified_gmt":"2025-05-18T08:07:26","slug":"excursion-roja-privada","status":"publish","type":"product","link":"https:\/\/gorgeousturkeytours.com\/es\/tours\/excursion-roja-privada\/","title":{"rendered":"Excursi\u00f3n Roja Privada"},"content":{"rendered":"[vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bb90px\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#ffffff\u00bb scene_position=\u00bbcenter\u00bb constrain_group_1=\u00bbyes\u00bb top_padding_tablet=\u00bb8%\u00bb bottom_padding_tablet=\u00bb8%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb id=\u00bbhome\u00bb overlay_strength=\u00bb0.5&#8243; gradient_direction=\u00bbtop_to_bottom\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bbstraight_section\u00bb][vc_column column_padding=\u00bbpadding-2-percent\u00bb column_padding_tablet=\u00bbno-extra-padding\u00bb column_padding_phone=\u00bbno-extra-padding\u00bb column_padding_position=\u00bbright\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb zindex=\u00bb100&#8243; gradient_direction=\u00bbleft_t_to_right_b\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb3\/5&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb offset=\u00bbvc_col-xs-12&#8243;][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb min_width=\u00bb47vh\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in-from-bottom\u00bb animation_easing=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb enable_border_animation=\u00bbtrue\u00bb][vc_column_text css_animation=\u00bbnone\u00bb css=\u00bb.vc_custom_1703418089353{margin-bottom: 20px !important;}\u00bb]\n<h2>Excursi\u00f3n Roja Privada<\/h2>\n[\/vc_column_text][vc_custom_heading text=\u00bbEste tour rojo privado de Capadocia sigue esencialmente el mismo itinerario que el tour rojo grupal est\u00e1ndar, pero esta opci\u00f3n le ofrece a usted y a su grupo la privacidad de su propio veh\u00edculo y la flexibilidad de cambiar el itinerario para adaptarlo.\u00bb font_container=\u00bbtag:p|font_size:20px|text_align:left|line_height:2em\u00bb use_theme_fonts=\u00bbyes\u00bb css_animation=\u00bbnone\u00bb][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]<strong>Itinerario:<\/strong><\/p>\n<ul>\n<li>Recogida en tu hotel a la hora acordada (recomendamos no m\u00e1s tarde de las 10.30 h).<\/li>\n<li>La primera parada es en el <strong>castillo de U\u00e7hisar<\/strong>, la formaci\u00f3n rocosa m\u00e1s alta de Capadocia. La gu\u00eda explicar\u00e1 c\u00f3mo surgi\u00f3 este incre\u00edble paisaje.<\/li>\n<li>En el museo al aire <strong>libre de G\u00f6reme<\/strong>, el gu\u00eda explicar\u00e1 la importancia del cristianismo y la vida mon\u00e1stica en Capadocia antes de dejarte libre para explorar las iglesias rupestres y los monasterios de los siglos X y XI con hermosos frescos pintados que representan escenas b\u00edblicas famosas.<\/li>\n<li>Vea las antiguas casas griegas en el pueblo de <strong>\u00c7avu\u015fin,<\/strong> abandonadas durante el intercambio de poblaci\u00f3n entre Grecia y Turqu\u00eda en 1924.<\/li>\n<li>Disfrute de un almuerzo\u00a0 en Avanos, que ofrece una amplia variedad de comida de Capadocia, que incluye mezes, ensaladas, carnes y platos y postres vegetarianos. (Opcional, no incluido)<\/li>\n<li><strong>A\u00fan en Avanos<\/strong>, visite un aut\u00e9ntico taller de cer\u00e1mica familiar ubicado en una cueva subterr\u00e1nea. La arcilla del r\u00edo K\u0131z\u0131l\u0131rmak (Rojo) fue utilizada por primera vez en la producci\u00f3n de cer\u00e1mica por los hititas antes de 1700 a. C. y contin\u00faa como una forma de arte en la actualidad. Vea a un maestro demostrar c\u00f3mo hacer una vasija y observe c\u00f3mo los pintores y vidriadores aplican sus delicados patrones. Pruebe usted mismo el torno de alfarero y haga su propia vasija \u00fanica si lo desea<\/li>\n<li><strong>En Pa\u015faba\u011f\u0131<\/strong> (tambi\u00e9n conocido como Valle de los Monjes debido a la Capilla de San Sime\u00f3n que se encuentra all\u00ed) pasee por los grupos inusuales de \u00abchimeneas de hadas\u00bb (formaciones rocosas) con forma de hongo de m\u00faltiples cabezas.<\/li>\n<li><strong>Valle de Devrent<\/strong> (\u00abValle de la imaginaci\u00f3n\u00bb): un valle impresionante donde se pueden observar formaciones rocosas naturales en muchas formas reconocibles en Capadocia, incluida la famosa roca en forma de camello.<\/li>\n<li>Regreso a su hotel aproximadamente<strong> a las 16:00 hrs.<\/strong><\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.5&#8243; width=\u00bb2\/5&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb offset=\u00bbvc_col-xs-12&#8243; column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb min_width_desktop=\u00bb43vw\u00bb min_width_tablet=\u00bb50vw\u00bb min_width_phone=\u00bb50vw\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; background_image=\u00bb1853&#8243; background_image_position=\u00bbcenter center\u00bb background_image_stacking=\u00bbdefault\u00bb background_image_loading=\u00bbdefault\u00bb column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.5&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbro-reveal-from-right\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][divider line_type=\u00bbNo Line\u00bb custom_height=\u00bb80vh\u00bb custom_height_tablet=\u00bb40vh\u00bb custom_height_phone=\u00bb300px\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row type=\u00bbfull_width_background\u00bb full_screen_row_position=\u00bbmiddle\u00bb column_margin=\u00bb90px\u00bb equal_height=\u00bbyes\u00bb content_placement=\u00bbmiddle\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bg_color=\u00bb#ffffff\u00bb scene_position=\u00bbcenter\u00bb constrain_group_1=\u00bbyes\u00bb top_padding_tablet=\u00bb8%\u00bb bottom_padding_tablet=\u00bb8%\u00bb text_color=\u00bbdark\u00bb text_align=\u00bbleft\u00bb row_border_radius=\u00bbnone\u00bb row_border_radius_applies=\u00bbbg\u00bb overflow=\u00bbvisible\u00bb overlay_strength=\u00bb0.5&#8243; gradient_direction=\u00bbtop_to_bottom\u00bb shape_divider_position=\u00bbbottom\u00bb bg_image_animation=\u00bbnone\u00bb shape_type=\u00bbstraight_section\u00bb gradient_type=\u00bbdefault\u00bb][vc_column column_padding=\u00bbpadding-2-percent\u00bb column_padding_tablet=\u00bbno-extra-padding\u00bb column_padding_phone=\u00bbno-extra-padding\u00bb column_padding_position=\u00bbright\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb column_position=\u00bbdefault\u00bb zindex=\u00bb100&#8243; gradient_direction=\u00bbleft_t_to_right_b\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb offset=\u00bbvc_col-xs-12&#8243;][vc_row_inner column_margin=\u00bb70px\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb top_padding=\u00bb25&#8243; bottom_padding=\u00bb15&#8243; text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbsmall_desktop\u00bb animation_type=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in-from-bottom\u00bb animation_easing=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css_animation=\u00bbnone\u00bb css=\u00bb.vc_custom_1703417954910{margin-bottom: 10px !important;}\u00bb]\n<h4>Inclusiones:<\/h4>\n[\/vc_column_text][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<ul>\n<li>Recogida y regreso al hotel.<\/li>\n<li>Transporte en minivan c\u00f3moda y moderna.<\/li>\n<li>Gu\u00eda profesional de habla espanhol.<\/li>\n<\/ul>\n<h4>Exclusiones:<\/h4>\n<ul>\n<li>Almuerzo y entradas<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbsmall_desktop\u00bb animation_type=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in-from-bottom\u00bb animation_easing=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][vc_column_text css_animation=\u00bbnone\u00bb css=\u00bb.vc_custom_1703417942823{margin-bottom: 10px !important;}\u00bb]\n<h4>Notas:<\/h4>\n[\/vc_column_text][vc_column_text css=\u00bb\u00bb text_direction=\u00bbdefault\u00bb]\n<ul>\n<li>Horario: 09:30 a 16:00 (hora recomendada: no m\u00e1s tarde de las 10:30 en invierno, no m\u00e1s tarde de las 13:00 en verano)<\/li>\n<li>Por favor, inf\u00f3rmenos del n\u00famero de personas en su grupo.<\/li>\n<li><\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/3&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in-from-bottom\u00bb animation_easing=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb column_padding_type=\u00bbdefault\u00bb gradient_type=\u00bbdefault\u00bb][vc_column_text css_animation=\u00bbnone\u00bb css=\u00bb.vc_custom_1703417933544{margin-bottom: 10px !important;}\u00bb]\n<h4>Cancelaciones:<\/h4>\n[\/vc_column_text][vc_column_text]\n<ul>\n<li>Las cancelaciones realizadas con <strong>m\u00e1s de 48 horas desde<\/strong> el inicio del tour no tendr\u00e1n cargo.<\/li>\n<li>Las cancelaciones realizadas <strong>entre 24-48 horas<\/strong> desde el inicio del tour tendr\u00e1n un cargo del 50% del monto adeudado.<\/li>\n<li>La no presentaci\u00f3n y las cancelaciones realizadas dentro de <strong>las 24 horas<\/strong> posteriores al comienzo de la hora de inicio se cobrar\u00e1n el 100% del monto adeudado<\/li>\n<\/ul>\n[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner column_margin=\u00bbdefault\u00bb column_direction=\u00bbdefault\u00bb column_direction_tablet=\u00bbdefault\u00bb column_direction_phone=\u00bbdefault\u00bb bottom_padding=\u00bb0px\u00bb bottom_padding_tablet=\u00bb40px\u00bb bottom_padding_phone=\u00bb40px\u00bb text_align=\u00bbleft\u00bb row_position=\u00bbdefault\u00bb row_position_tablet=\u00bbinherit\u00bb row_position_phone=\u00bbinherit\u00bb overflow=\u00bbvisible\u00bb pointer_events=\u00bball\u00bb][vc_column_inner column_padding=\u00bbno-extra-padding\u00bb column_padding_tablet=\u00bbinherit\u00bb column_padding_phone=\u00bbinherit\u00bb column_padding_position=\u00bball\u00bb column_element_direction_desktop=\u00bbdefault\u00bb column_element_spacing=\u00bbdefault\u00bb desktop_text_alignment=\u00bbdefault\u00bb tablet_text_alignment=\u00bbdefault\u00bb phone_text_alignment=\u00bbdefault\u00bb background_color_opacity=\u00bb1&#8243; background_hover_color_opacity=\u00bb1&#8243; column_backdrop_filter=\u00bbnone\u00bb column_shadow=\u00bbnone\u00bb column_border_radius=\u00bbnone\u00bb column_link_target=\u00bb_self\u00bb overflow=\u00bbvisible\u00bb gradient_direction=\u00bbleft_to_right\u00bb overlay_strength=\u00bb0.3&#8243; width=\u00bb1\/1&#8243; tablet_width_inherit=\u00bbdefault\u00bb animation_type=\u00bbdefault\u00bb enable_animation=\u00bbtrue\u00bb animation=\u00bbfade-in-from-bottom\u00bb animation_easing=\u00bbdefault\u00bb bg_image_animation=\u00bbnone\u00bb border_type=\u00bbsimple\u00bb column_border_width=\u00bbnone\u00bb column_border_style=\u00bbsolid\u00bb][nectar_cta btn_style=\u00bbarrow-animation\u00bb heading_tag=\u00bbh6&#8243; button_color=\u00bbaccent-color\u00bb text_color=\u00bb#ffffff\u00bb button_border_thickness=\u00bb0px\u00bb link_type=\u00bbregular\u00bb alignment=\u00bbleft\u00bb alignment_tablet=\u00bbdefault\u00bb alignment_phone=\u00bbdefault\u00bb display=\u00bbblock\u00bb display_tablet=\u00bbinherit\u00bb display_phone=\u00bbinherit\u00bb link_text=\u00bbReservar ahora\u00bb padding_top=\u00bb15&#8243; padding_right=\u00bb35&#8243; padding_bottom=\u00bb15&#8243; padding_left=\u00bb35&#8243; url=\u00bb#\u00bb][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>Este tour rojo privado de Capadocia sigue esencialmente el mismo itinerario que el tour rojo grupal est\u00e1ndar, pero esta opci\u00f3n le ofrece a usted<\/p>\n","protected":false},"featured_media":3567,"template":"","meta":[],"product_brand":[],"product_cat":[186,183],"product_tag":[],"class_list":{"0":"post-3566","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tours-privados","7":"product_cat-capadocia","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-variable"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/gorgeousturkeytours.com\/es\/wp-json\/wp\/v2\/product\/3566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gorgeousturkeytours.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gorgeousturkeytours.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gorgeousturkeytours.com\/es\/wp-json\/wp\/v2\/media\/3567"}],"wp:attachment":[{"href":"https:\/\/gorgeousturkeytours.com\/es\/wp-json\/wp\/v2\/media?parent=3566"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gorgeousturkeytours.com\/es\/wp-json\/wp\/v2\/product_brand?post=3566"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gorgeousturkeytours.com\/es\/wp-json\/wp\/v2\/product_cat?post=3566"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gorgeousturkeytours.com\/es\/wp-json\/wp\/v2\/product_tag?post=3566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}